{"id":238,"date":"2026-04-07T19:31:34","date_gmt":"2026-04-07T17:31:34","guid":{"rendered":"https:\/\/www.lettereadioealluomo.com\/wordpress\/?page_id=238"},"modified":"2026-04-27T20:55:50","modified_gmt":"2026-04-27T18:55:50","slug":"il-cipresso","status":"publish","type":"page","link":"https:\/\/www.lettereadioealluomo.com\/wordpress\/il-cipresso\/","title":{"rendered":"IL CIPRESSO"},"content":{"rendered":"\n<pre class=\"wp-block-verse has-text-align-center has-vivid-red-color has-text-color has-background has-link-color wp-elements-1\" id=\"masthead\" style=\"background-color:#edfffd;font-size:13px\">       <a href=\"http:\/\/www.lettereadioealluomo.com\/Index.htm\">Home<\/a>  | <a href=\"#TESTO\">Testo della Poesia<\/a>. | <a href=\"#Fine\">Vai gi\u00f9 <\/a> |  <a href=\"http:\/\/www.lettereadioealluomo.com\/wordpress\/index-wordpress\">Index WordPress <\/a>|<\/pre>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-src=\"https:\/\/www.lettereadioealluomo.com\/wordpress\/wp-content\/uploads\/2026\/04\/1000005491-edited-1024x768.jpg\" alt=\"\" class=\"wp-image-292 lazyload\" data-srcset=\"https:\/\/www.lettereadioealluomo.com\/wordpress\/wp-content\/uploads\/2026\/04\/1000005491-edited-1024x768.jpg 1024w, https:\/\/www.lettereadioealluomo.com\/wordpress\/wp-content\/uploads\/2026\/04\/1000005491-edited-300x225.jpg 300w, https:\/\/www.lettereadioealluomo.com\/wordpress\/wp-content\/uploads\/2026\/04\/1000005491-edited-768x576.jpg 768w, https:\/\/www.lettereadioealluomo.com\/wordpress\/wp-content\/uploads\/2026\/04\/1000005491-edited-1536x1151.jpg 1536w, https:\/\/www.lettereadioealluomo.com\/wordpress\/wp-content\/uploads\/2026\/04\/1000005491-edited-2048x1535.jpg 2048w, https:\/\/www.lettereadioealluomo.com\/wordpress\/wp-content\/uploads\/2026\/04\/1000005491-edited-360x270.jpg 360w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/768;\" \/><figcaption class=\"wp-element-caption\">Monte San Savino visto da Sud-ovest. <br><br><em>Cipressi nella fascia della vegetazione perimetrale . Abbelliscono e personalizzano l&#8217;immagine del Paese.<\/em><\/figcaption><\/figure>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-large\"><img decoding=\"async\" width=\"1484\" height=\"1980\" data-src=\"https:\/\/www.lettereadioealluomo.com\/wordpress\/wp-content\/uploads\/2026\/04\/ALEL21-395-edited.jpg\" alt=\"\" class=\"wp-image-289 lazyload\" data-srcset=\"https:\/\/www.lettereadioealluomo.com\/wordpress\/wp-content\/uploads\/2026\/04\/ALEL21-395-edited.jpg 1484w, https:\/\/www.lettereadioealluomo.com\/wordpress\/wp-content\/uploads\/2026\/04\/ALEL21-395-edited-225x300.jpg 225w, https:\/\/www.lettereadioealluomo.com\/wordpress\/wp-content\/uploads\/2026\/04\/ALEL21-395-edited-767x1024.jpg 767w, https:\/\/www.lettereadioealluomo.com\/wordpress\/wp-content\/uploads\/2026\/04\/ALEL21-395-edited-768x1025.jpg 768w, https:\/\/www.lettereadioealluomo.com\/wordpress\/wp-content\/uploads\/2026\/04\/ALEL21-395-edited-1151x1536.jpg 1151w, https:\/\/www.lettereadioealluomo.com\/wordpress\/wp-content\/uploads\/2026\/04\/ALEL21-395-edited-202x270.jpg 202w\" data-sizes=\"(max-width: 1484px) 100vw, 1484px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1484px; --smush-placeholder-aspect-ratio: 1484\/1980;\" \/><figcaption class=\"wp-element-caption\">Scorcio di viale. Fattoria La Vialla (Castiglion Fibocchi -AR-). <br><em><br>L&#8217;antichit\u00e0 e il medioevo conoscono l&#8217;uso del Cipresso come legname, frangivento, funerario. L&#8217;uso estetico per abbellire il paesaggio, comincia col Rinascimento italiano e il Vignola (1507-73) . La borghesia illuminata toscana tra sette-ottocento, assume il Cipresso in modo massiccio; fino a caratterizzare il paesaggio toscano. Ci\u00f2 fanno per gusto personale, ma anche in compagnia dei notabili del Grand Tour. Questi ammiravano e talvolta esportavano l&#8217;usanza in Europa; quelli si facevano ammirare e gareggiavano per costruire viali e ville; giardini monumentali.<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<pre class=\"wp-block-verse has-text-align-center has-vivid-red-color has-text-color has-background has-link-color wp-elements-2\" id=\"TESTO\" style=\"background-color:#edfffd;font-size:13px\"><a href=\"#masthead\">TESTO<\/a><\/pre>\n\n\n\n<pre class=\"wp-block-verse has-text-align-center has-background\" style=\"background-color:#edfffd\"><br>O cipresso di gran toscana<br>che da sera a mattina<br>in tutta l'urbe mediterranea<br>rendi pi\u00f9 bella e vigorosa, la vita<br>e la grande passeggiata<br> italiana e nostrana,<br><br>\u00e8 tempo della tua lode,<br>perch\u00e9 sono secoli <br>che come un eroe fiero e alto<br>non temente la guerra,<br><br>preferisci tuttavia <br>la pace e l'onest\u00e0<br>quotidiana, guardi <br>l'ampio paesaggio<br>lodando Dio <br>e gli uomini tutti.<br><br>E lo fai per mezzo della <br>tua fiamma verde <br>che il sole natio <br>e i venti forieri,<br>alimentano incessantemente.<br><br>La alimentano<br>verso il Cielo divino <br>e insieme tanto umano;<br>tanto umano da usare<br>perfino le chiome dei cipressi,<br>per ricordare e manifestare<br>la sua bont\u00e0 e bellezza;<br>tanto umano<br>cio\u00e8 tanto innamorato<br>degli umani; <br>in tal senso, questo Cielo<br>\u00e8 pi\u00f9 umano di ogni <br>altra cosa umana,<br>perch\u00e9 per quanto <br>radicalmente diverso <br>da questo mondo, <br>rimane tuttavia<br>palpito umano ineguagliabile,<br> vocazione ultima<br>e casa eterna prima,<br>di tutti gli uomini<\/pre>\n\n\n\n<p class=\"has-text-align-center has-vivid-red-color has-text-color has-link-color wp-elements-3 wp-block-paragraph\" id=\"masthead\"><a href=\"http:\/\/www.lettereadioealluomo.com\/morte-cipresso-sanleo.htm\">Cipresso di San Leo<\/a> | <a href=\"#masthead\">Torna su<\/a> | <a href=\"https:\/\/www.lettereadioealluomo.com\/moraldi-cipresso-papa.htm\">Cipresso di Verucchio<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-vivid-red-color has-text-color has-link-color wp-elements-4 wp-block-paragraph\" id=\"Fine\"><a href=\"#masthead\">Fine<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Home | Testo della Poesia. | Vai gi\u00f9 | Index WordPress | TESTO O cipresso di gran toscanache da sera a mattinain tutta l&#8217;urbe mediterranearendi pi\u00f9 bella e vigorosa, la vitae la grande passeggiata italiana e nostrana,\u00e8 tempo della tua lode,perch\u00e9 sono secoli che come un eroe fiero e altonon temente la guerra,preferisci tuttavia la pace e l&#8217;onest\u00e0quotidiana, guardi l&#8217;ampio paesaggiolodando Dio e gli uomini tutti.E lo fai per mezzo della tua fiamma verde che il sole natio e i&#8230;<\/p>\n<p class=\"read-more\"><a class=\"btn btn-default\" href=\"https:\/\/www.lettereadioealluomo.com\/wordpress\/il-cipresso\/\">Leggi tutto<span class=\"screen-reader-text\"> Leggi tutto<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-238","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.lettereadioealluomo.com\/wordpress\/wp-json\/wp\/v2\/pages\/238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lettereadioealluomo.com\/wordpress\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.lettereadioealluomo.com\/wordpress\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.lettereadioealluomo.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lettereadioealluomo.com\/wordpress\/wp-json\/wp\/v2\/comments?post=238"}],"version-history":[{"count":94,"href":"https:\/\/www.lettereadioealluomo.com\/wordpress\/wp-json\/wp\/v2\/pages\/238\/revisions"}],"predecessor-version":[{"id":918,"href":"https:\/\/www.lettereadioealluomo.com\/wordpress\/wp-json\/wp\/v2\/pages\/238\/revisions\/918"}],"wp:attachment":[{"href":"https:\/\/www.lettereadioealluomo.com\/wordpress\/wp-json\/wp\/v2\/media?parent=238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}